{"id":399,"date":"2023-04-18T02:54:33","date_gmt":"2023-04-18T02:54:33","guid":{"rendered":"https:\/\/powertisment.com\/?post_type=product&#038;p=399"},"modified":"2023-04-18T02:54:45","modified_gmt":"2023-04-18T02:54:45","slug":"sparkling-honey-dew","status":"publish","type":"product","link":"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/","title":{"rendered":"Sparkling Honey Dew"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":428,"template":"","meta":{"_themeisle_gutenberg_block_has_review":false},"product_cat":[25],"product_tag":[],"class_list":["post-399","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-beverage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sparkling Honey Dew - E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sparkling Honey Dew - E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/\" \/>\n<meta property=\"og:site_name\" content=\"E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RekaFlavourConcentrates\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-18T02:54:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myvapeflavour.com\/sa\/Media\/2023\/04\/Sparkling-Honey-Dew.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/\",\"url\":\"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/\",\"name\":\"Sparkling Honey Dew - E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates\",\"isPartOf\":{\"@id\":\"https:\/\/myvapeflavour.com\/sa\/#website\"},\"datePublished\":\"2023-04-18T02:54:33+00:00\",\"dateModified\":\"2023-04-18T02:54:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/myvapeflavour.com\/sa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sparkling Honey Dew\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/myvapeflavour.com\/sa\/#website\",\"url\":\"https:\/\/myvapeflavour.com\/sa\/\",\"name\":\"E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates\",\"description\":\"Vape, Vape Juice, E-Juice Flavour Concentrates\",\"publisher\":{\"@id\":\"https:\/\/myvapeflavour.com\/sa\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/myvapeflavour.com\/sa\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/myvapeflavour.com\/sa\/#organization\",\"name\":\"E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates\",\"url\":\"https:\/\/myvapeflavour.com\/sa\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/myvapeflavour.com\/sa\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/myvapeflavour.com\/sa\/Media\/2023\/05\/cropped-Reka-Flavour-Concentrate-Logo-240x60px.png\",\"contentUrl\":\"https:\/\/myvapeflavour.com\/sa\/Media\/2023\/05\/cropped-Reka-Flavour-Concentrate-Logo-240x60px.png\",\"width\":240,\"height\":60,\"caption\":\"E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates\"},\"image\":{\"@id\":\"https:\/\/myvapeflavour.com\/sa\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/RekaFlavourConcentrates\",\"https:\/\/www.tiktok.com\/@RekaFlavourConcentrates\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sparkling Honey Dew - E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/","og_locale":"en_US","og_type":"article","og_title":"Sparkling Honey Dew - E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates","og_url":"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/","og_site_name":"E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates","article_publisher":"https:\/\/www.facebook.com\/RekaFlavourConcentrates","article_modified_time":"2023-04-18T02:54:45+00:00","og_image":[{"width":350,"height":350,"url":"https:\/\/myvapeflavour.com\/sa\/Media\/2023\/04\/Sparkling-Honey-Dew.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/","url":"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/","name":"Sparkling Honey Dew - E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates","isPartOf":{"@id":"https:\/\/myvapeflavour.com\/sa\/#website"},"datePublished":"2023-04-18T02:54:33+00:00","dateModified":"2023-04-18T02:54:45+00:00","breadcrumb":{"@id":"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/myvapeflavour.com\/sa\/product\/sparkling-honey-dew\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/myvapeflavour.com\/sa\/"},{"@type":"ListItem","position":2,"name":"Sparkling Honey Dew"}]},{"@type":"WebSite","@id":"https:\/\/myvapeflavour.com\/sa\/#website","url":"https:\/\/myvapeflavour.com\/sa\/","name":"E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates","description":"Vape, Vape Juice, E-Juice Flavour Concentrates","publisher":{"@id":"https:\/\/myvapeflavour.com\/sa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myvapeflavour.com\/sa\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/myvapeflavour.com\/sa\/#organization","name":"E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates","url":"https:\/\/myvapeflavour.com\/sa\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/myvapeflavour.com\/sa\/#\/schema\/logo\/image\/","url":"https:\/\/myvapeflavour.com\/sa\/Media\/2023\/05\/cropped-Reka-Flavour-Concentrate-Logo-240x60px.png","contentUrl":"https:\/\/myvapeflavour.com\/sa\/Media\/2023\/05\/cropped-Reka-Flavour-Concentrate-Logo-240x60px.png","width":240,"height":60,"caption":"E Juice Flavour Manufacturers | Vape Flavour Manufacturer | Vape Juice Flavour Manufacturers | Vape Flavor Manufacturers | E-Juice Flavour Manufacturers | Reka Flavour Concentrates"},"image":{"@id":"https:\/\/myvapeflavour.com\/sa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RekaFlavourConcentrates","https:\/\/www.tiktok.com\/@RekaFlavourConcentrates"]}]}},"_links":{"self":[{"href":"https:\/\/myvapeflavour.com\/sa\/wp-json\/wp\/v2\/product\/399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myvapeflavour.com\/sa\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/myvapeflavour.com\/sa\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myvapeflavour.com\/sa\/wp-json\/wp\/v2\/media\/428"}],"wp:attachment":[{"href":"https:\/\/myvapeflavour.com\/sa\/wp-json\/wp\/v2\/media?parent=399"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/myvapeflavour.com\/sa\/wp-json\/wp\/v2\/product_cat?post=399"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/myvapeflavour.com\/sa\/wp-json\/wp\/v2\/product_tag?post=399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}