{"id":1129,"date":"2023-07-28T04:38:40","date_gmt":"2023-07-28T04:38:40","guid":{"rendered":"https:\/\/myvapeflavour.com\/vn\/?post_type=product&#038;p=1129"},"modified":"2023-07-28T04:38:42","modified_gmt":"2023-07-28T04:38:42","slug":"cam-do-blood-orange","status":"publish","type":"product","link":"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/","title":{"rendered":"Cam \u0110\u1ecf (Blood Orange)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":373,"template":"","meta":{"_themeisle_gutenberg_block_has_review":false},"product_cat":[24],"product_tag":[],"class_list":["post-1129","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-fruits"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cam \u0110\u1ecf (Blood Orange) - Myvapeflavour.com - Reka Flavour Concentrates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cam \u0110\u1ecf (Blood Orange) - Myvapeflavour.com - Reka Flavour Concentrates\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/\" \/>\n<meta property=\"og:site_name\" content=\"Myvapeflavour.com - Reka Flavour Concentrates\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RekaFlavourConcentrates\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-28T04:38:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/\",\"url\":\"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/\",\"name\":\"Cam \u0110\u1ecf (Blood Orange) - Myvapeflavour.com - Reka Flavour Concentrates\",\"isPartOf\":{\"@id\":\"https:\/\/myvapeflavour.com\/vn\/#website\"},\"datePublished\":\"2023-07-28T04:38:40+00:00\",\"dateModified\":\"2023-07-28T04:38:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/myvapeflavour.com\/vn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cam \u0110\u1ecf (Blood Orange)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/myvapeflavour.com\/vn\/#website\",\"url\":\"https:\/\/myvapeflavour.com\/vn\/\",\"name\":\"Myvapeflavour.com - Reka Flavour Concentrates\",\"description\":\"Vape, Vape Juice, E-Juice Flavour Concentrates\",\"publisher\":{\"@id\":\"https:\/\/myvapeflavour.com\/vn\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/myvapeflavour.com\/vn\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/myvapeflavour.com\/vn\/#organization\",\"name\":\"Myvapeflavour.com - Reka Flavour Concentrates\",\"url\":\"https:\/\/myvapeflavour.com\/vn\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/myvapeflavour.com\/vn\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/myvapeflavour.com\/vn\/Media\/2023\/05\/cropped-Reka-Flavour-Concentrate-Logo-240x60px.png\",\"contentUrl\":\"https:\/\/myvapeflavour.com\/vn\/Media\/2023\/05\/cropped-Reka-Flavour-Concentrate-Logo-240x60px.png\",\"width\":240,\"height\":60,\"caption\":\"Myvapeflavour.com - Reka Flavour Concentrates\"},\"image\":{\"@id\":\"https:\/\/myvapeflavour.com\/vn\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/RekaFlavourConcentrates\",\"https:\/\/www.tiktok.com\/@RekaFlavourConcentrates\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cam \u0110\u1ecf (Blood Orange) - Myvapeflavour.com - Reka Flavour Concentrates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/","og_locale":"en_US","og_type":"article","og_title":"Cam \u0110\u1ecf (Blood Orange) - Myvapeflavour.com - Reka Flavour Concentrates","og_url":"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/","og_site_name":"Myvapeflavour.com - Reka Flavour Concentrates","article_publisher":"https:\/\/www.facebook.com\/RekaFlavourConcentrates","article_modified_time":"2023-07-28T04:38:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/","url":"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/","name":"Cam \u0110\u1ecf (Blood Orange) - Myvapeflavour.com - Reka Flavour Concentrates","isPartOf":{"@id":"https:\/\/myvapeflavour.com\/vn\/#website"},"datePublished":"2023-07-28T04:38:40+00:00","dateModified":"2023-07-28T04:38:42+00:00","breadcrumb":{"@id":"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/myvapeflavour.com\/vn\/product\/cam-do-blood-orange\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/myvapeflavour.com\/vn\/"},{"@type":"ListItem","position":2,"name":"Cam \u0110\u1ecf (Blood Orange)"}]},{"@type":"WebSite","@id":"https:\/\/myvapeflavour.com\/vn\/#website","url":"https:\/\/myvapeflavour.com\/vn\/","name":"Myvapeflavour.com - Reka Flavour Concentrates","description":"Vape, Vape Juice, E-Juice Flavour Concentrates","publisher":{"@id":"https:\/\/myvapeflavour.com\/vn\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myvapeflavour.com\/vn\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/myvapeflavour.com\/vn\/#organization","name":"Myvapeflavour.com - Reka Flavour Concentrates","url":"https:\/\/myvapeflavour.com\/vn\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/myvapeflavour.com\/vn\/#\/schema\/logo\/image\/","url":"https:\/\/myvapeflavour.com\/vn\/Media\/2023\/05\/cropped-Reka-Flavour-Concentrate-Logo-240x60px.png","contentUrl":"https:\/\/myvapeflavour.com\/vn\/Media\/2023\/05\/cropped-Reka-Flavour-Concentrate-Logo-240x60px.png","width":240,"height":60,"caption":"Myvapeflavour.com - Reka Flavour Concentrates"},"image":{"@id":"https:\/\/myvapeflavour.com\/vn\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RekaFlavourConcentrates","https:\/\/www.tiktok.com\/@RekaFlavourConcentrates"]}]}},"_links":{"self":[{"href":"https:\/\/myvapeflavour.com\/vn\/wp-json\/wp\/v2\/product\/1129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myvapeflavour.com\/vn\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/myvapeflavour.com\/vn\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myvapeflavour.com\/vn\/wp-json\/wp\/v2\/media\/373"}],"wp:attachment":[{"href":"https:\/\/myvapeflavour.com\/vn\/wp-json\/wp\/v2\/media?parent=1129"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/myvapeflavour.com\/vn\/wp-json\/wp\/v2\/product_cat?post=1129"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/myvapeflavour.com\/vn\/wp-json\/wp\/v2\/product_tag?post=1129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}